{"id":1667,"date":"2020-10-10T10:04:41","date_gmt":"2020-10-10T10:04:41","guid":{"rendered":"https:\/\/www.vocazone.ch\/privacy-policy\/"},"modified":"2023-01-20T16:38:40","modified_gmt":"2023-01-20T16:38:40","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/","title":{"rendered":"D\u00e9claration de confidentialit\u00e9"},"content":{"rendered":"\n<p>Verantwortliche Stelle im Sinne der Datenschutzgesetze, insbesondere der EU-Datenschutzgrundverordnung (DSGVO), ist:<\/p>\n\n\n\n<p>VocaZone <br>by nadlo GmbH<br>Lukas Keller<br>Cordulaplatz 8<br>5400 Baden<\/p>\n\n\n\n<p>Telefon: +41 62 521 34 30<br>E-Mail: angebot@vocazone.ch<br>WebSite: https:\/\/www.vocazone.ch\/<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Allgemeiner Hinweis<\/h2>\n\n\n\n<p>Gest\u00fctzt auf Artikel 13 der schweizerischen Bundesverfassung und den datenschutzrechtlichen Bestimmungen des Bundes (Datenschutzgesetz, DSG) hat jede Person Anspruch auf Schutz ihrer Privatsph\u00e4re sowie auf Schutz vor Missbrauch ihrer pers\u00f6nlichen Daten. Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<p>In Zusammenarbeit mit unseren Hosting-Providern bem\u00fchen wir uns, die Datenbanken so gut wie m\u00f6glich vor fremden Zugriffen, Verlusten, Missbrauch oder vor F\u00e4lschung zu sch\u00fctzen.<\/p>\n\n\n\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n\n\n\n<p>Durch die Nutzung dieser Website erkl\u00e4ren Sie sich mit der Erhebung, Verarbeitung und Nutzung von Daten gem\u00e4ss der nachfolgenden Beschreibung einverstanden. Diese Website kann grunds\u00e4tzlich ohne Registrierung besucht werden. Dabei werden Daten wie beispielsweise aufgerufene Seiten bzw. Namen der abgerufenen Datei, Datum und Uhrzeit zu statistischen Zwecken auf dem Server gespeichert, ohne dass diese Daten unmittelbar auf Ihre Person bezogen werden. Personenbezogene Daten, insbesondere Name, Adresse oder E-Mail-Adresse werden soweit m\u00f6glich auf freiwilliger Basis erhoben. Ohne Ihre Einwilligung erfolgt keine Weitergabe der Daten an Dritte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bearbeitung von Personendaten<\/h2>\n\n\n\n<p>Personendaten sind alle Angaben, die sich auf eine bestimmte oder bestimmbare Person beziehen. Eine betroffene Person ist eine Person, \u00fcber die Personendaten bearbeitet werden. Bearbeiten umfasst jeden Umgang mit Personendaten, unabh\u00e4ngig von den angewandten Mitteln und Verfahren, insbesondere das Aufbewahren, Bekanntgeben, Beschaffen, L\u00f6schen, Speichern, Ver\u00e4ndern, Vernichten und Verwenden von Personendaten.<\/p>\n\n\n\n<p>Wir bearbeiten Personendaten im Einklang mit dem schweizerischen Datenschutzrecht. Im \u00dcbrigen bearbeiten wir \u2013 soweit und sofern die EU-DSGVO anwendbar ist \u2013 Personendaten gem\u00e4ss folgenden Rechtsgrundlagen im Zusammenhang mit Art. 6 Abs. 1 DSGVO:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>lit. a) Bearbeitung von Personendaten mit Einwilligung der betroffenen Person.<\/li>\n\n\n\n<li>lit. b) Bearbeitung von Personendaten zur Erf\u00fcllung eines Vertrages mit der betroffenen Person sowie zur Durchf\u00fchrung entsprechender vorvertraglicher Massnahmen.<\/li>\n\n\n\n<li>lit. c) Bearbeitung von Personendaten zur Erf\u00fcllung einer rechtlichen Verpflichtung, der wir gem\u00e4ss allenfalls anwendbarem Recht der EU oder gem\u00e4ss allenfalls anwendbarem Recht eines Landes, in dem die DSGVO ganz oder teilweise anwendbar ist, unterliegen.<\/li>\n\n\n\n<li>lit. d) Bearbeitung von Personendaten um lebenswichtige Interessen der betroffenen Person oder einer anderen nat\u00fcrlichen Person zu sch\u00fctzen.<\/li>\n\n\n\n<li>lit. f) Bearbeitung von Personendaten um die berechtigten Interessen von uns oder von Dritten zu wahren, sofern nicht die Grundfreiheiten und Grundrechte sowie Interessen der betroffenen Person \u00fcberwiegen. Berechtigte Interessen sind insbesondere unser betriebswirtschaftliches Interesse, unsere Website bereitstellen zu k\u00f6nnen, die Informationssicherheit, die Durchsetzung von eigenen rechtlichen Anspr\u00fcchen und die Einhaltung von schweizerischem Recht.<\/li>\n<\/ul>\n\n\n\n<p>Wir bearbeiten Personendaten f\u00fcr jene Dauer, die f\u00fcr den jeweiligen Zweck oder die jeweiligen Zwecke erforderlich ist. Bei l\u00e4nger dauernden Aufbewahrungspflichten aufgrund von gesetzlichen und sonstigen Pflichten, denen wir unterliegen, schr\u00e4nken wir die Bearbeitung entsprechend ein.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Datenschutzerkl\u00e4rung f\u00fcr Cookies<\/h2>\n\n\n\n<p>Diese Website verwendet Cookies. Das sind kleine Textdateien, die es m\u00f6glich machen, auf dem Endger\u00e4t des Nutzers spezifische, auf den Nutzer bezogene Informationen zu speichern, w\u00e4hrend er die Website nutzt. Cookies erm\u00f6glichen es, insbesondere Nutzungsh\u00e4ufigkeit und Nutzeranzahl der Seiten zu ermitteln, Verhaltensweisen der Seitennutzung zu analysieren, aber auch unser Angebot kundenfreundlicher zu gestalten. Cookies bleiben \u00fcber das Ende einer Browser-Sitzung gespeichert und k\u00f6nnen bei einem erneuten Seitenbesuch wieder aufgerufen werden. Wenn Sie das nicht w\u00fcnschen, sollten Sie Ihren Internetbrowser so einstellen, dass er die Annahme von Cookies verweigert.<\/p>\n\n\n\n<p>Ein genereller Widerspruch gegen den Einsatz der zu Zwecken des Onlinemarketing eingesetzten Cookies kann bei einer Vielzahl der Dienste, vor allem im Fall des Trackings, \u00fcber die US-amerikanische Seite <a href=\"http:\/\/www.aboutads.info\/choices\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.aboutads.info\/choices\/<\/a> oder die EU-Seite <a href=\"http:\/\/www.youronlinechoices.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.youronlinechoices.com\/<\/a> erkl\u00e4rt werden. Des Weiteren kann die Speicherung von Cookies mittels deren Abschaltung in den Einstellungen des Browsers erreicht werden. Bitte beachten Sie, dass dann gegebenenfalls nicht alle Funktionen dieses Onlineangebotes genutzt werden k\u00f6nnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Datenschutzerkl\u00e4rung f\u00fcr SSL-\/TLS-Verschl\u00fcsselung<\/h2>\n\n\n\n<p>Diese Website nutzt aus Gr\u00fcnden der Sicherheit und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel der Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL-\/TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u00ab\u00a0http:\/\/\u00a0\u00bb auf \u00ab\u00a0https:\/\/\u00a0\u00bb wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n\n\n\n<p>Wenn die SSL bzw. TLS Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Datenschutzerkl\u00e4rung f\u00fcr Server-Log-Files<\/h2>\n\n\n\n<p>Der Provider dieser Website erhebt und speichert automatisch Informationen in so genannten Server-Log Files, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Browsertyp und Browserversion<\/li>\n\n\n\n<li>verwendetes Betriebssystem<\/li>\n\n\n\n<li>Referrer URL<\/li>\n\n\n\n<li>Hostname des zugreifenden Rechners<\/li>\n\n\n\n<li>Uhrzeit der Serveranfrage<\/li>\n<\/ul>\n\n\n\n<p>Diese Daten sind nicht bestimmten Personen zuordenbar. Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen. Wir behalten uns vor, diese Daten nachtr\u00e4glich zupr\u00fcfen, wenn uns konkrete Anhaltspunkte f\u00fcr eine rechtswidrige Nutzung bekannt werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dienste von Dritten<\/h2>\n\n\n\n<p>Diese Website verwenden allenfalls Google Maps f\u00fcr das Einbetten von Karten, Google Invisible reCAPTCHA f\u00fcr den Schutz gegen Bots und Spam sowie YouTube f\u00fcr das Einbetten von Videos.<\/p>\n\n\n\n<p>Diese Dienste der amerikanischen Google LLC verwenden unter anderem Cookies und infolgedessen werden Daten an Google in den USA \u00fcbertragen, wobei wir davon ausgehen, dass in diesem Rahmen kein personenbezogenes Tracking allein durch die Nutzung unserer Website stattfindet.<\/p>\n\n\n\n<p>Google hat sich verpflichtet, einen angemessenen Datenschutz gem\u00e4ss dem amerikanisch-europ\u00e4ischen und dem amerikanisch-schweizerischen Privacy Shield zu gew\u00e4hrleisten.<\/p>\n\n\n\n<p>Weitere Informationen finden sich in der <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">Datenschutzerkl\u00e4rung von Google<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Datenschutzerkl\u00e4rung f\u00fcr Kontaktformular<\/h2>\n\n\n\n<p>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Verwendung von Google Maps<\/h2>\n\n\n\n<p>Diese Website nutzt das Angebot von Google Maps. Dadurch k\u00f6nnen wir Ihnen interaktive Karten direkt in der Website anzeigen und erm\u00f6glichen Ihnen die komfortable Nutzung der Karten-Funktion. Durch den Besuch auf der Website erh\u00e4lt Google die Information, dass Sie die entsprechende Unterseite unserer Website aufgerufen haben. Dies erfolgt unabh\u00e4ngig davon, ob Google ein Nutzerkonto bereitstellt, \u00fcber das Sie eingeloggt sind, oder ob kein Nutzerkonto besteht. Wenn Sie bei Google eingeloggt sind, werden Ihre Daten direkt Ihrem Konto zugeordnet. Wenn Sie die Zuordnung mit Ihrem Profil bei Google nicht w\u00fcnschen, m\u00fcssen Sie sich vor Aktivierung des Buttons ausloggen. Google speichert Ihre Daten als Nutzungsprofile und nutzt sie f\u00fcr Zwecke der Werbung, Marktforschung und\/oder bedarfsgerechten Gestaltung seiner Website. Eine solche Auswertung erfolgt insbesondere (selbst f\u00fcr nicht eingeloggte Nutzer) zur Erbringung von bedarfsgerechter Werbung und um andere Nutzer des sozialen Netzwerks \u00fcber Ihre Aktivit\u00e4ten auf unserer Website zu informieren. Ihnen steht ein Widerspruchsrecht zu gegen die Bildung dieser Nutzerprofile, wobei Sie sich zur Aus\u00fcbung dessen an Google richten m\u00fcssen. Weitere Informationen zu Zweck und Umfang der Datenerhebung und ihrer Verarbeitung durch Google erhalten Sie neben weiteren Informationen zu Ihren diesbez\u00fcglichen Rechten und Einstellungsm\u00f6glichkeiten zum Schutze Ihrer Privatsph\u00e4re unter: <a href=\"http:\/\/www.google.de\/intl\/de\/policies\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">www.google.de\/intl\/de\/policies\/privacy<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Google AdWords<\/h2>\n\n\n\n<p>Diese Website nutzt das Google Conversion-Tracking. Sind Sie \u00fcber eine von Google geschaltete Anzeige auf unsere WebSite gelangt, wird von Google Adwords ein Cookie auf Ihrem Rechner gesetzt. Das Cookie f\u00fcr Conversion-Tracking wird gesetzt, wenn ein Nutzer auf eine von Google geschaltete Anzeige klickt. Diese Cookies verlieren nach 30 Tagen ihre G\u00fcltigkeit und dienen nicht der pers\u00f6nlichen Identifizierung. Besucht der Nutzer bestimmte Seiten unserer Website und das Cookie ist noch nicht abgelaufen, k\u00f6nnen wir und Google erkennen, dass der Nutzer auf die Anzeige geklickt hat und zu dieser Seite weitergeleitet wurde. Jeder Google AdWords-Kunde erh\u00e4lt ein anderes Cookie. Cookies k\u00f6nnen somit nicht \u00fcber die Websites von AdWords-Kunden nachverfolgt werden. Die mithilfe des Conversion-Cookies eingeholten Informationen dienen dazu, Conversion-Statistiken f\u00fcr AdWords-Kunden zu erstellen, die sich f\u00fcr Conversion-Tracking entschieden haben. Die Kunden erfahren die Gesamtanzahl der Nutzer, die auf ihre Anzeige geklickt haben und zu einer mit einem Conversion-Tracking-Tag versehenen Seite weitergeleitet wurden. Sie erhalten jedoch keine Informationen, mit denen sich Nutzer pers\u00f6nlich identifizieren lassen.<\/p>\n\n\n\n<p>M\u00f6chten Sie nicht am Tracking teilnehmen, k\u00f6nnen Sie das hierf\u00fcr erforderliche Setzen eines Cookies ablehnen \u2013 etwa per Browser-Einstellung, die das automatische Setzen von Cookies generell deaktiviert oder Ihren Browser so einstellen, dass Cookies von der Domain \u201egoogleleadservices.com\u201c blockiert werden.<\/p>\n\n\n\n<p>Bitte beachten Sie, dass Sie die Opt-out-Cookies nicht l\u00f6schen d\u00fcrfen, solange Sie keine Aufzeichnung von Messdaten w\u00fcnschen. Haben Sie alle Ihre Cookies im Browser gel\u00f6scht, m\u00fcssen Sie das jeweilige Opt-out Cookie erneut setzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Einsatz von Google Remarketing<\/h2>\n\n\n\n<p>Diese Website verwendet die Remarketing-Funktion der Google Inc. Die Funktion dient dazu, Websitenbesuchern innerhalb des Google-Werbenetzwerks interessenbezogene Werbeanzeigen zu pr\u00e4sentieren. Im Browser des Websitenbesuchers wird ein sog. \u201eCookie\u201c gespeichert, der es erm\u00f6glicht, den Besucher wiederzuerkennen, wenn dieser Websiten aufruft, die dem Werbenetzwerk von Google angeh\u00f6ren. Auf diesen Seiten k\u00f6nnen dem Besucher Werbeanzeigen pr\u00e4sentiert werden, die sich auf Inhalte beziehen, die der Besucher zuvor auf Websiten aufgerufen hat, die die Remarketing Funktion von Google verwenden.<\/p>\n\n\n\n<p>Nach eigenen Angaben erhebt Google bei diesem Vorgang keine personenbezogenen Daten. Sollten Sie die Funktion Remarketing von Google dennoch nicht w\u00fcnschen, k\u00f6nnen Sie diese grunds\u00e4tzlich deaktivieren, indem Sie die entsprechenden Einstellungen unter <a href=\"http:\/\/www.google.com\/settings\/ads\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.google.com\/settings\/ads<\/a> vornehmen. Alternativ k\u00f6nnen Sie den Einsatz von Cookies f\u00fcr interessenbezogene Werbung \u00fcber die Werbenetzwerkinitiative deaktivieren, indem Sie den Anweisungen unter <a href=\"http:\/\/www.networkadvertising.org\/managing\/opt_out.asp\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.networkadvertising.org\/managing\/opt_out.asp<\/a> folgen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Datenschutzerkl\u00e4rung f\u00fcr Google Analytics<\/h2>\n\n\n\n<p>Diese Website benutzt Google Analytics, einen Webanalysedienst der Google Ireland Limited. Wenn der Verantwortliche f\u00fcr die Datenverarbeitung auf dieser Website ausserhalb des Europ\u00e4ischen Wirtschaftsraumes oder der Schweiz sitzt, dann erfolgt die Google Analytics Datenverarbeitung durch Google LLC. Google LLC und Google Ireland Limited werden nachfolgend \u00abGoogle\u00bb genannt.<\/p>\n\n\n\n<p>\u00dcber die gewonnenen Statistiken k\u00f6nnen wir unser Angebot verbessern und f\u00fcr Sie als Nutzer interessanter ausgestalten. Diese Website verwendet Google Analytics zudem f\u00fcr eine ger\u00e4te\u00fcbergreifende Analyse von Besucherstr\u00f6men, die \u00fcber eine User-ID durchgef\u00fchrt wird. Sofern Sie \u00fcber ein Google-Benutzerkonto verf\u00fcgen, k\u00f6nnen Sie in den dortigen Einstellungen unter \u00abMeine Daten\u00bb, \u00abpers\u00f6nliche Daten\u00bb die ger\u00e4te\u00fcbergreifende Analyse Ihrer Nutzung deaktivieren.<\/p>\n\n\n\n<p>Rechtsgrundlage f\u00fcr die Nutzung von Google Analytics ist Art. 6 Abs. 1 S. 1 lit. f DS-GVO. Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt. Wir weisen Sie darauf hin, dass auf dieser Website Google Analytics um den Code \u00ab_anonymizeIp();\u00bb erweitert wurde, um eine anonymisierte Erfassung von IP-Adressen zu gew\u00e4hrleisten. Dadurch werden IP-Adressen gek\u00fcrzt weiterverarbeitet, eine Personenbeziehbarkeit kann damit ausgeschlossen werden. Soweit den \u00fcber Sie erhobenen Daten ein Personenbezug zukommt, wird dieser also sofort ausgeschlossen und die personenbezogenen Daten damit umgehend gel\u00f6scht.<\/p>\n\n\n\n<p>Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Im Auftrag des Betreibers dieser Website wird Google diese Informationen benutzen, um Ihre Nutzung der Website auszuwerten, um Reports \u00fcber die Websitenaktivit\u00e4ten zusammenzustellen und um weitere mit der Websitennutzung und der Internetnutzung verbundene Dienstleistungen gegen\u00fcber dem Websitenbetreiber zu erbringen. F\u00fcr die Ausnahmef\u00e4lle, in denen personenbezogene Daten in die USA \u00fcbertragen werden, hat sich Google dem EU-US Privacy Shield unterworfen, <a href=\"https:\/\/www.privacyshield.gov\/EU-US-Framework\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.privacyshield.gov\/EU-US-Framework<\/a>.<\/p>\n\n\n\n<p>Google Analytics verwendet Cookies. Die durch den Cookie erzeugten Informationen \u00fcber Ihre Benutzung dieser Website werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Sie k\u00f6nnen die Speicherung der Cookies durch eine entsprechende Einstellung Ihrer Browser-Software verhindern; wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website vollumf\u00e4nglich werden nutzen k\u00f6nnen. Sie k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch das Cookie erzeugten und auf Ihre Nutzung der Website bezogenen Daten (inkl. Ihrer IP-Adresse) an Google sowie die Verarbeitung dieser Daten durch Google verhindern, indem sie das unter dem folgenden Link verf\u00fcgbare Browser-Plugin herunterladen und installieren: <a href=\"https:\/\/www.swissanwalt.ch\/de\/gaoptout.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Google Analytics deaktivieren<\/a>.<\/p>\n\n\n\n<p>Ausserdem k\u00f6nnen Sie die Nutzung von Google Analytics auch verhindern, indem sie auf diesen Link klicken: <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">Google Analytics deaktivieren<\/a>. Hierdurch wird ein sog. opt-out Cookie auf ihrem Datentr\u00e4ger gespeichert, der die Verarbeitung personenbezogener Daten durch Google Analytics verhindert. Bitte beachten Sie, dass bei einem L\u00f6schen s\u00e4mtlicher Cookies auf Ihrem Endger\u00e4t auch diese Opt-out-Cookies gel\u00f6scht werden, d.h., dass Sie erneut die Opt-out-Cookies setzen m\u00fcssen, wenn Sie weiterhin diese Form der Datenerhebung verhindern wollen. Die Opt-out-Cookies sind pro Browser und Rechner\/Endger\u00e4t gesetzt und m\u00fcssen daher f\u00fcr jeden Browser, Rechner oder anderes Endger\u00e4t gesondert aktiviert werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Datenschutzerkl\u00e4rung f\u00fcr Google Ads<\/h2>\n\n\n\n<p>Diese Website nutzt das Online-Marketing-Tool Google Ads von Google (\u00abGoogle Ads\u00bb). Google Ads setzt Cookies ein, um f\u00fcr die Nutzer relevante Anzeigen zu schalten, die Berichte zur Kampagnenleistung zu verbessern oder um zu vermeiden, dass ein Nutzer die gleichen Anzeigen mehrmals sieht. \u00dcber eine Cookie-ID erfasst Google, welche Anzeigen in welchem Browser geschaltet werden und kann so verhindern, dass diese mehrfach angezeigt werden. Dar\u00fcber hinaus kann Google Ads mithilfe von Cookie-IDs sog. Conversions erfassen, die Bezug zu Anzeigenanfragen haben. Das ist etwa der Fall, wenn ein Nutzer eine Google Ads-Anzeige sieht und sp\u00e4ter mit demselben Browser die Website des Werbetreibenden aufruft und dort etwas kauft. Laut Google enthalten Google Ads-Cookies keine personenbezogenen Informationen.<\/p>\n\n\n\n<p>Aufgrund der eingesetzten Marketing-Tools baut Ihr Browser automatisch eine direkte Verbindung mit dem Server von Google auf. Durch die Einbindung von Google Ads erh\u00e4lt Google die Information, dass Sie den entsprechenden Teil unseres Internetauftritts aufgerufen oder eine Anzeige von uns angeklickt haben. Sofern Sie bei einem Dienst von Google registriert sind, kann Google den Besuch Ihrem Account zuordnen. Selbst wenn Sie nicht bei Google registriert sind bzw. sich nicht eingeloggt haben, besteht die M\u00f6glichkeit, dass Google Ihre IP-Adresse in Erfahrung bringt und speichert.<\/p>\n\n\n\n<p>Sie k\u00f6nnen die Teilnahme an diesem Tracking-Verfahren auf verschiedene Weise verhindern:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>durch eine entsprechende Einstellung Ihrer Browser-Software, insbesondere f\u00fchrt die Unterdr\u00fcckung von Drittcookies dazu, dass Sie keine Anzeigen von Drittanbietern erhalten;<\/li>\n\n\n\n<li>durch Deaktivierung der Cookies f\u00fcr Conversion-Tracking, indem Sie Ihren Browser so einstellen, dass Cookies von der Domain \u00abwww.googleadservices.com\u00bb blockiert werden, <a href=\"https:\/\/adssettings.google.com\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/adssettings.google.com<\/a>, wobei diese Einstellung gel\u00f6scht wird, wenn Sie Ihre Cookies l\u00f6schen;<\/li>\n\n\n\n<li>durch Deaktivierung der interessenbezogenen Anzeigen der Anbieter, die Teil der Selbstregulierungs-Kampagne \u00abAbout Ads\u00bb sind, \u00fcber den Link <a href=\"http:\/\/www.aboutads.info\/choices\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.aboutads.info\/choices<\/a>, wobei diese Einstellung gel\u00f6scht wird, wenn Sie Ihre Cookies l\u00f6schen;<\/li>\n\n\n\n<li>durch dauerhafte Deaktivierung in Ihren Browsern Firefox, Internetexplorer oder Google Chrome unter dem Link <a href=\"http:\/\/www.google.com\/settings\/ads\/plugin\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.com\/settings\/ads\/plugin<\/a>. Wir weisen Sie darauf hin, dass Sie in diesem Fall gegebenenfalls nicht alle Funktionen dieses Angebots vollumf\u00e4nglich nutzen k\u00f6nnen.<\/li>\n<\/ul>\n\n\n\n<p>Rechtsgrundlage f\u00fcr die Verarbeitung Ihrer Daten ist eine Interessenabw\u00e4gung, wonach der vorstehend geschilderten Verarbeitung Ihrer personenbezogenen Daten keine \u00fcberwiegenden gegenteiligen Interessen Ihrerseits entgegenstehen (Art. 6 Abs. 1 S. 1 lit. f DSGVO). Weitere Informationen zu Google Ads von Google erhalten Sie unter <a href=\"https:\/\/ads.google.com\/intl\/de_DE\/home\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/ads.google.com\/intl\/de_DE\/home\/<\/a>, sowie zum Datenschutz bei Google allgemein: <a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.de\/intl\/de\/policies\/privacy<\/a>. Alternativ k\u00f6nnen Sie die Website der Network Advertising Initiative (NAI) unter <a href=\"http:\/\/www.networkadvertising.org\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.networkadvertising.org<\/a> besuchen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Datenschutzerkl\u00e4rung f\u00fcr Facebook<\/h2>\n\n\n\n<p>Diese Website verwendet Funktionen von Facebook Inc., 1601 S. California Ave, Palo Alto, CA 94304, USA . Bei Aufruf unserer Seiten mit Facebook-Plug-Ins wird eine Verbindung zwischen Ihrem Browser und den Servern von Facebook aufgebaut. Dabei werden bereits Daten an Facebook \u00fcbertragen. Besitzen Sie einen Facebook-Account, k\u00f6nnen diese Daten damit verkn\u00fcpft werden. Wenn Sie keine Zuordnung dieser Daten zu Ihrem Facebook-Account w\u00fcnschen, loggen Sie sich bitte vor dem Besuch unserer Seite bei Facebook aus. Interaktionen, insbesondere das Nutzen einer Kommentarfunktion oder das Anklicken eines \u201eLike\u201c- oder \u201eTeilen\u201c-Buttons werden ebenfalls an Facebook weitergegeben. Mehr erfahren Sie unter <a href=\"https:\/\/de-de.facebook.com\/about\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/de-de.facebook.com\/about\/privacy<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Datenschutzerkl\u00e4rung f\u00fcr Instagram<\/h2>\n\n\n\n<p>Auf unserer Website sind Funktionen des Dienstes Instagram eingebunden. Diese Funktionen werden angeboten durch die Instagram Inc., 1601 Willow Road, Menlo Park, CA, 94025, USA integriert. Wenn Sie in Ihrem Instagram-Account eingeloggt sind k\u00f6nnen Sie durch Anklicken des Instagram-Buttons die Inhalte unserer Seiten mit Ihrem Instagram-Profil verlinken. Dadurch kann Instagram den Besuch unserer Seiten Ihrem Benutzerkonto zuordnen. Wir weisen darauf hin, dass wir als Anbieter der Seiten keine Kenntnis vom Inhalt der \u00fcbermittelten Daten sowie deren Nutzung durch Instagram erhalten.<\/p>\n\n\n\n<p>Weitere Informationen hierzu finden Sie in der Datenschutzerkl\u00e4rung von Instagram: <a href=\"https:\/\/instagram.com\/about\/legal\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/instagram.com\/about\/legal\/privacy\/<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c4nderungen<\/h2>\n\n\n\n<p>Wir k\u00f6nnen diese Datenschutzerkl\u00e4rung jederzeit ohne Vorank\u00fcndigung anpassen. Es gilt die jeweils aktuelle, auf unserer Website publizierte Fassung. Soweit die Datenschutzerkl\u00e4rung Teil einer Vereinbarung mit Ihnen ist, werden wir Sie im Falle einer Aktualisierung \u00fcber die \u00c4nderung per E-Mail oder auf andere geeignete Weise informieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fragen an den Datenschutzbeauftragten<\/h2>\n\n\n\n<p>Wenn Sie Fragen zum Datenschutz haben, schreiben Sie uns bitte eine E-Mail oder wenden Sie sich direkt an die f\u00fcr den Datenschutz zu Beginn der Datenschutzerkl\u00e4rung aufgef\u00fchrten, verantwortlichen Person in unserer Organisation.<\/p>\n\n\n\n<p>Baden, 08.11.2020<br>Quelle: <a href=\"https:\/\/www.swissanwalt.ch\" target=\"_blank\" rel=\"noreferrer noopener\">SwissAnwalt<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Verantwortliche Stelle im Sinne der Datenschutzgesetze, insbesondere der EU-Datenschutzgrundverordnung (DSGVO), ist: VocaZone by nadlo GmbHLukas KellerCordulaplatz 85400 Baden Telefon: +41 62 521 34 30E-Mail: angebot@vocazone.chWebSite: https:\/\/www.vocazone.ch\/ Allgemeiner Hinweis Gest\u00fctzt auf Artikel 13 der schweizerischen Bundesverfassung und den datenschutzrechtlichen Bestimmungen des Bundes (Datenschutzgesetz, DSG) hat jede Person Anspruch auf Schutz ihrer Privatsph\u00e4re sowie auf Schutz vor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1667","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutzerkl\u00e4rung | Bearbeitung von Personendaten - VocaZone<\/title>\n<meta name=\"description\" content=\"Diese Website verwendet Cookies. Personendaten sind alle Angaben, die sich auf eine bestimmte oder bestimmbare Person beziehen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung | Bearbeitung von Personendaten - VocaZone\" \/>\n<meta property=\"og:description\" content=\"Diese Website verwendet Cookies. Personendaten sind alle Angaben, die sich auf eine bestimmte oder bestimmbare Person beziehen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"VocaZone\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-20T16:38:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/\",\"url\":\"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/\",\"name\":\"Datenschutzerkl\u00e4rung | Bearbeitung von Personendaten - VocaZone\",\"isPartOf\":{\"@id\":\"https:\/\/www.vocazone.ch\/fr\/#website\"},\"datePublished\":\"2020-10-10T10:04:41+00:00\",\"dateModified\":\"2023-01-20T16:38:40+00:00\",\"description\":\"Diese Website verwendet Cookies. Personendaten sind alle Angaben, die sich auf eine bestimmte oder bestimmbare Person beziehen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vocazone.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9claration de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vocazone.ch\/fr\/#website\",\"url\":\"https:\/\/www.vocazone.ch\/fr\/\",\"name\":\"VocaZone\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vocazone.ch\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung | Bearbeitung von Personendaten - VocaZone","description":"Diese Website verwendet Cookies. Personendaten sind alle Angaben, die sich auf eine bestimmte oder bestimmbare Person beziehen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/","og_locale":"fr_FR","og_type":"article","og_title":"Datenschutzerkl\u00e4rung | Bearbeitung von Personendaten - VocaZone","og_description":"Diese Website verwendet Cookies. Personendaten sind alle Angaben, die sich auf eine bestimmte oder bestimmbare Person beziehen.","og_url":"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/","og_site_name":"VocaZone","article_modified_time":"2023-01-20T16:38:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/","url":"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/","name":"Datenschutzerkl\u00e4rung | Bearbeitung von Personendaten - VocaZone","isPartOf":{"@id":"https:\/\/www.vocazone.ch\/fr\/#website"},"datePublished":"2020-10-10T10:04:41+00:00","dateModified":"2023-01-20T16:38:40+00:00","description":"Diese Website verwendet Cookies. Personendaten sind alle Angaben, die sich auf eine bestimmte oder bestimmbare Person beziehen.","breadcrumb":{"@id":"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vocazone.ch\/fr\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vocazone.ch\/fr\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vocazone.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9claration de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.vocazone.ch\/fr\/#website","url":"https:\/\/www.vocazone.ch\/fr\/","name":"VocaZone","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vocazone.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.vocazone.ch\/fr\/wp-json\/wp\/v2\/pages\/1667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vocazone.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vocazone.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vocazone.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vocazone.ch\/fr\/wp-json\/wp\/v2\/comments?post=1667"}],"version-history":[{"count":0,"href":"https:\/\/www.vocazone.ch\/fr\/wp-json\/wp\/v2\/pages\/1667\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vocazone.ch\/fr\/wp-json\/wp\/v2\/media?parent=1667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}